{"id":26,"count":3,"description":"","link":"https:\/\/testv95.demowebsitelinks.com\/Taze-X\/tag\/perfume\/","name":"Perfume","slug":"perfume","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Taze-X\/wp-json\/wp\/v2\/tags\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Taze-X\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Taze-X\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Taze-X\/wp-json\/wp\/v2\/posts?tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}