{"id":10272,"date":"2025-07-15T13:39:37","date_gmt":"2025-07-15T13:39:37","guid":{"rendered":"https:\/\/testv81.demowebsitelinks.com\/Robert-RogersV2\/?page_id=10272"},"modified":"2026-03-30T23:57:32","modified_gmt":"2026-03-30T23:57:32","slug":"rare-books","status":"publish","type":"page","link":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/rare-books\/","title":{"rendered":"Rare Books"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10272\" class=\"elementor elementor-10272\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-9bee1b7 elementor-section-content-middle wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bee1b7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8fc83fc\" data-id=\"8fc83fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec8636a elementor-section-content-middle elementor-reverse-mobile wd-section-stretch elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"ec8636a\" data-element_type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;wd_sweet_wave&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg width=\"100%\" height=\"50px\" viewBox=\"0 0 1920 80\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"wd-divider\" preserveAspectRatio=\"none\">\n<path class=\"elementor-shape-fill\" d=\"M1920,60s-169.5,20-510,20S850.5,20,510,20,0,60,0,60V0H1920Z\" \/>\n<\/svg>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2f32e6\" data-id=\"a2f32e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8813c79 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"8813c79\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\">Discover Rare Reads<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title set-cont-mb-s reset-last-child wd-fontsize-xs\">\n\t\t\t\t\t<p>Step into a curated selection of works that go beyond ordinary reading. The <i>Rare Books<\/i> collection by Robert Rogers brings together deeply personal, emotionally resonant writings that reflect a lifetime of experience, thought, and storytelling.<\/p><p>Each book in this collection captures a distinct perspective\u2014ranging from love and longing to memory, conflict, and reflection. These are not simply stories to be read, but moments to be felt. Every page carries a sense of authenticity, shaped by real emotions and lived experiences.<\/p><p>What makes these works rare is not just their limited availability, but the depth they hold. They invite readers to pause, reflect, and connect with themes that are both intimate and universal.<\/p><p>This collection is designed for readers who seek more than entertainment\u2014for those who value meaning, nuance, and the quiet power of words.<\/p><p>Explore the collection and discover works that stay with you long after the final page.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-271ff10 wd-section-stretch-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"271ff10\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-179cf0f\" data-id=\"179cf0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-6506e6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6506e6f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5e9b862\" data-id=\"5e9b862\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78008b0 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"78008b0\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\">Love is Mysterious<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a36afb color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"3a36afb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84d1d7b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"84d1d7b\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-element elementor-element-84d1d7b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"84d1d7b\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><p>An exploration of love in its most enigmatic form. This collection dives into the complexity, beauty, and unpredictability of human connection. Thought-provoking and deeply expressive, it reveals that love is not meant to be understood\u2014only felt.<\/p><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08a4f21 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"08a4f21\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-sink\" href=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/product\/love-is-mysterious\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Treat Yourself<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19f8405 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"19f8405\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"617\" height=\"206\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1.png\" class=\"attachment-full size-full wp-image-10853\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1.png 617w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1-400x134.png 400w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1-430x144.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1-150x50.png 150w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f8804c6\" data-id=\"f8804c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c01047f elementor-widget elementor-widget-image\" data-id=\"c01047f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/asdsdcc.png\" class=\"attachment-full size-full wp-image-10836\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/asdsdcc.png 684w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/asdsdcc-200x300.png 200w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/asdsdcc-534x800.png 534w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/asdsdcc-430x644.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/asdsdcc-150x225.png 150w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc57d2b wd-section-stretch-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc57d2b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e6d89e9\" data-id=\"e6d89e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aeb1ccc elementor-widget elementor-widget-image\" data-id=\"aeb1ccc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/image1-1-e1774910467613.png\" class=\"attachment-full size-full wp-image-10821\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/image1-1-e1774910467613.png 684w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/image1-1-e1774910467613-200x300.png 200w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/image1-1-e1774910467613-534x800.png 534w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/image1-1-e1774910467613-430x644.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/image1-1-e1774910467613-150x225.png 150w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-272ca23\" data-id=\"272ca23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-9d756c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d756c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-489fd08\" data-id=\"489fd08\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f41ae8 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"0f41ae8\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\">I Dream Her \u2013 Mend My Heart<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cda3d50 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"cda3d50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84d1d7b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"84d1d7b\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><p class=\"elementor-heading-title elementor-size-default\"><span data-teams=\"true\">A deeply emotional journey through longing, desire, and the search for true love. This collection explores the delicate space between dreams and reality, where love exists in its purest yet most fragile form. Written with sincerity, it speaks to those who have loved, lost, and hoped again.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3ceb8b elementor-align-right elementor-widget elementor-widget-button\" data-id=\"a3ceb8b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-sink\" href=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/product\/i-dream-her-mend-my-heart\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Treat Yourself<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-107cbff elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"107cbff\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"617\" height=\"206\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc.png\" class=\"attachment-full size-full wp-image-10855\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc.png 617w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc-400x134.png 400w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc-430x144.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc-150x50.png 150w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9b0431 wd-section-stretch-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9b0431\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5550956\" data-id=\"5550956\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-67ad660 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67ad660\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-88f3412\" data-id=\"88f3412\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff1d5c4 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"ff1d5c4\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\">Best of Times - Love Poems<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0023c2f color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"0023c2f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84d1d7b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"84d1d7b\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-element elementor-element-84d1d7b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"84d1d7b\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><p class=\"elementor-heading-title elementor-size-default\"><span data-teams=\"true\">A poetic reflection on love, memory, and the moments that define us. Best of Times captures the beauty of fleeting experiences and the emotions that stay long after they pass. A timeless collection for those who understand the depth of connection and the quiet power of remembrance.<\/span><\/p><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-460008a elementor-align-left elementor-widget elementor-widget-button\" data-id=\"460008a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-sink\" href=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/product\/best-of-times\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Treat Yourself<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-818d75b elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"818d75b\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"617\" height=\"206\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1.png\" class=\"attachment-full size-full wp-image-10853\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1.png 617w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1-400x134.png 400w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1-430x144.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/arrow_left_white-1-150x50.png 150w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d4bbb21\" data-id=\"d4bbb21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2c0adc elementor-widget elementor-widget-image\" data-id=\"f2c0adc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/7yuh-jnmk.png\" class=\"attachment-full size-full wp-image-10827\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/7yuh-jnmk.png 684w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/7yuh-jnmk-200x300.png 200w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/7yuh-jnmk-534x800.png 534w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/7yuh-jnmk-430x644.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/7yuh-jnmk-150x225.png 150w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f31047 wd-section-stretch-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f31047\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6876408\" data-id=\"6876408\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-934db18 elementor-widget elementor-widget-image\" data-id=\"934db18\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sadsc.png\" class=\"attachment-full size-full wp-image-10835\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sadsc.png 684w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sadsc-200x300.png 200w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sadsc-534x800.png 534w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sadsc-430x644.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sadsc-150x225.png 150w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-19149a1\" data-id=\"19149a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-88cd2c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88cd2c5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9ca2346\" data-id=\"9ca2346\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c40271 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"8c40271\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\">The Feeling Lingers<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-825980c color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"825980c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84d1d7b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"84d1d7b\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><p class=\"elementor-heading-title elementor-size-default\"><span data-teams=\"true\">Some emotions never fade\u2014they evolve. The Feeling Lingers is a moving collection that captures the echoes of love, memory, and moments that continue to live within us. Subtle yet powerful, it invites readers into a space of reflection and quiet understanding.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ef03a3 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"5ef03a3\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"617\" height=\"206\" src=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc.png\" class=\"attachment-full size-full wp-image-10855\" alt=\"\" srcset=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc.png 617w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc-400x134.png 400w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc-430x144.png 430w, https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-content\/uploads\/2026\/03\/sacasddscc-150x50.png 150w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4a4522 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"d4a4522\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-sink\" href=\"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/product\/the-feeling-lingers-memories\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Treat Yourself<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Discover Rare Reads Step into a curated selection of works that go beyond ordinary reading. The Rare Books collection by<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-10272","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/pages\/10272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/comments?post=10272"}],"version-history":[{"count":46,"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/pages\/10272\/revisions"}],"predecessor-version":[{"id":10873,"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/pages\/10272\/revisions\/10873"}],"wp:attachment":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Robert-RogersV2\/wp-json\/wp\/v2\/media?parent=10272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}