{"id":74,"count":1,"description":"","link":"https:\/\/testv95.demowebsitelinks.com\/Pretty-Girl-Problemz\/category\/healthcare-ai\/","name":"Healthcare AI","slug":"healthcare-ai","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Pretty-Girl-Problemz\/wp-json\/wp\/v2\/categories\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Pretty-Girl-Problemz\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Pretty-Girl-Problemz\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/testv95.demowebsitelinks.com\/Pretty-Girl-Problemz\/wp-json\/wp\/v2\/posts?categories=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}